{"id":747,"date":"2025-02-11T10:48:47","date_gmt":"2025-02-11T09:48:47","guid":{"rendered":"https:\/\/trasportimiranda.it\/?p=747"},"modified":"2025-02-11T10:53:13","modified_gmt":"2025-02-11T09:53:13","slug":"il-governo-riduce-i-fondi-destinati-allautotrasporto-ugge-chiama-a-raccolta-la-presidenza-unatras","status":"publish","type":"post","link":"https:\/\/trasportimiranda.it\/de\/il-governo-riduce-i-fondi-destinati-allautotrasporto-ugge-chiama-a-raccolta-la-presidenza-unatras\/","title":{"rendered":"Il Governo riduce i fondi destinati all&#8217;autotrasporto, Ugg\u00e8 chiama a raccolta la Presidenza Unatras"},"content":{"rendered":"<p>La decisione del Governo di ridurre i finanziamenti gi\u00e0 pattuiti per il settore dell\u2019autotrasporto ha scatenato una dura reazione da parte di Unatras. Paolo Ugg\u00e8, presidente dell&#8217;associazione, ha definito l&#8217;azione come \u201cinaccettabile\u201d e ha avvertito che questa mossa potrebbe mettere seriamente a rischio i rapporti con l\u2019esecutivo, creando un clima di forte conflitto con gravi conseguenze per l\u2019intero comparto. Subito dopo l&#8217;annuncio della riduzione dei fondi, Ugg\u00e8 ha convocato con urgenza una riunione straordinaria della Presidenza di Unatras per la settimana prossima, con l\u2019intento di definire misure rapide e concrete in risposta a quella che considera una mossa unilaterale. &#8220;La convocazione della Presidenza \u00e8 urgente per trovare una risposta decisa a un atteggiamento che mina i rapporti con il Governo&#8221;, ha spiegato Ugg\u00e8, mettendo in chiaro che questa situazione potrebbe sfociare in un periodo di forti tensioni. Ugg\u00e8 ha poi ricordato che, negli ultimi mesi, sono venuti meno anche altri impegni presi dal Governo, come le riunioni periodiche per discutere le problematiche del settore. &#8220;Oltre al fatto che le riunioni promesse non si sono tenute, ora il Governo procede senza alcun confronto, riducendo i fondi che avevamo concordato&#8221;, ha affermato con forza il presidente di Unatras. Secondo<br \/>\n \u2019associazione, questa scelta \u00e8 una \u201cmossa miope e priva di ascolto\u201d, che arriva in un momento particolarmente delicato per un settore che sta gi\u00e0 affrontando difficolt\u00e0 enormi, sia economiche che logistiche. Unatras sostiene che il Governo, agendo unilateralmente, non solo danneggia il comparto, ma rischia di compromettere la sua stessa stabilit\u00e0. In risposta a quanto accaduto, Ugg\u00e8 ha deciso di convocare un incontro straordinario della Presidenza di Unatras, durante il quale verranno definite azioni dirette e tempestive per difendere le imprese di autotrasporto, che<br \/>\npotrebbero subire gravi danni da questi tagli. Nonostante la contrariet\u00e0 alla decisione, Unatras ribadisce la sua disponibilit\u00e0 al dialogo, ma insiste sul fatto che qualsiasi confronto deve avvenire nel rispetto degli accordi precedentemente sottoscritti. Secondo l\u2019associazione, l\u2019atteggiamento del Governo non \u00e8 solo ingiustificato, ma rischia di indebolire un settore cruciale per l\u2019economia del Paese.<\/p>","protected":false},"excerpt":{"rendered":"<p>La decisione del Governo di ridurre i finanziamenti gi\u00e0 pattuiti per il settore dell\u2019autotrasporto ha scatenato una dura reazione da parte di Unatras. Paolo Ugg\u00e8, presidente dell&#8217;associazione, ha definito l&#8217;azione come \u201cinaccettabile\u201d e ha avvertito che questa mossa potrebbe mettere seriamente a rischio i rapporti con l\u2019esecutivo, creando un clima di forte conflitto con gravi [&#8230;]\n","protected":false},"author":1,"featured_media":749,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/trasportimiranda.it\/de\/wp-json\/wp\/v2\/posts\/747"}],"collection":[{"href":"https:\/\/trasportimiranda.it\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trasportimiranda.it\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trasportimiranda.it\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/trasportimiranda.it\/de\/wp-json\/wp\/v2\/comments?post=747"}],"version-history":[{"count":1,"href":"https:\/\/trasportimiranda.it\/de\/wp-json\/wp\/v2\/posts\/747\/revisions"}],"predecessor-version":[{"id":748,"href":"https:\/\/trasportimiranda.it\/de\/wp-json\/wp\/v2\/posts\/747\/revisions\/748"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trasportimiranda.it\/de\/wp-json\/wp\/v2\/media\/749"}],"wp:attachment":[{"href":"https:\/\/trasportimiranda.it\/de\/wp-json\/wp\/v2\/media?parent=747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trasportimiranda.it\/de\/wp-json\/wp\/v2\/categories?post=747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trasportimiranda.it\/de\/wp-json\/wp\/v2\/tags?post=747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}